{"id":14,"count":1,"description":"","link":"https:\/\/schmidt-schoeneiche.de\/pms\/category\/analog\/","name":"Analog","slug":"analog","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/schmidt-schoeneiche.de\/pms\/wp-json\/wp\/v2\/categories\/14","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/schmidt-schoeneiche.de\/pms\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/schmidt-schoeneiche.de\/pms\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/schmidt-schoeneiche.de\/pms\/wp-json\/wp\/v2\/posts?categories=14"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}